{"id":13,"count":1,"description":"","link":"https:\/\/continentalis.eu\/es\/etiqueta\/declaracion-de-entrada\/","name":"declaraci\u00f3n de entrada","slug":"declaracion-de-entrada","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>declaration of entry Archives - Continentalis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/continentalis.eu\/es\/etiqueta\/declaracion-de-entrada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"declaration of entry Archives - Continentalis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/continentalis.eu\/es\/etiqueta\/declaracion-de-entrada\/\" \/>\n<meta property=\"og:site_name\" content=\"Continentalis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/\",\"url\":\"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/\",\"name\":\"declaration of entry Archives - Continentalis\",\"isPartOf\":{\"@id\":\"https:\/\/continentalis.eu\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/continentalis.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"declaration of entry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/continentalis.eu\/#website\",\"url\":\"https:\/\/continentalis.eu\/\",\"name\":\"Continentalis\",\"description\":\"Immigration Documents Made Simple - Background Checks, Apostilles, Translations\",\"publisher\":{\"@id\":\"https:\/\/continentalis.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/continentalis.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/continentalis.eu\/#organization\",\"name\":\"Continentalis\",\"url\":\"https:\/\/continentalis.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/continentalis.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/continentalis.eu\/wp-content\/uploads\/continentalis-logo-1.svg\",\"contentUrl\":\"https:\/\/continentalis.eu\/wp-content\/uploads\/continentalis-logo-1.svg\",\"width\":822,\"height\":149,\"caption\":\"Continentalis\"},\"image\":{\"@id\":\"https:\/\/continentalis.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/3666583106956808\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"declaration of entry Archives - Continentalis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/continentalis.eu\/es\/etiqueta\/declaracion-de-entrada\/","og_locale":"es_ES","og_type":"article","og_title":"declaration of entry Archives - Continentalis","og_url":"https:\/\/continentalis.eu\/es\/etiqueta\/declaracion-de-entrada\/","og_site_name":"Continentalis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/","url":"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/","name":"declaraci\u00f3n de entrada Archivos - Continentalis","isPartOf":{"@id":"https:\/\/continentalis.eu\/#website"},"breadcrumb":{"@id":"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/continentalis.eu\/tag\/declaration-of-entry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/continentalis.eu\/"},{"@type":"ListItem","position":2,"name":"declaration of entry"}]},{"@type":"WebSite","@id":"https:\/\/continentalis.eu\/#website","url":"https:\/\/continentalis.eu\/","name":"Continental","description":"Documentos de inmigraci\u00f3n simplificados - Verificaciones de antecedentes, apostillas, traducciones","publisher":{"@id":"https:\/\/continentalis.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/continentalis.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/continentalis.eu\/#organization","name":"Continental","url":"https:\/\/continentalis.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/continentalis.eu\/#\/schema\/logo\/image\/","url":"https:\/\/continentalis.eu\/wp-content\/uploads\/continentalis-logo-1.svg","contentUrl":"https:\/\/continentalis.eu\/wp-content\/uploads\/continentalis-logo-1.svg","width":822,"height":149,"caption":"Continentalis"},"image":{"@id":"https:\/\/continentalis.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/3666583106956808"]}]}},"_links":{"self":[{"href":"https:\/\/continentalis.eu\/es\/wp-json\/wp\/v2\/tags\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/continentalis.eu\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/continentalis.eu\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/continentalis.eu\/es\/wp-json\/wp\/v2\/posts?tags=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}